{"id":10560,"date":"2024-02-16T01:00:00","date_gmt":"2024-02-16T00:00:00","guid":{"rendered":"https:\/\/www.mesmedias.be\/magazine\/tresors-le-magazine-des-fouilleurs-2\/"},"modified":"2026-07-08T16:02:48","modified_gmt":"2026-07-08T14:02:48","slug":"tresors-le-magazine-des-fouilleurs-2","status":"publish","type":"product","link":"https:\/\/www.mesmedias.be\/nl\/magazine\/tresors-le-magazine-des-fouilleurs-2\/","title":{"rendered":"Tr\u00e9sors, le Magazine des Fouilleurs n\u00b02"},"content":{"rendered":"<p><strong>Tr\u00e9sors, le magazine des Fouilleurs<\/strong>\u00a0est un incontournable pour les passionn\u00e9s de d\u00e9tection de m\u00e9taux, d\u2019orpillage et de p\u00eache \u00e0 l\u2019aimant. Paru tous les trois mois en kiosque depuis\u00a0<strong>2005<\/strong>, ce magazine r\u00e9f\u00e9rence d\u00e9voile les tr\u00e9sors d\u00e9couverts en France, que ce soit avec un d\u00e9tecteur de m\u00e9taux, un aimant ou une b\u00e2t\u00e9e. Dans chaque num\u00e9ro, vous trouverez des r\u00e9cits captivants sur des d\u00e9couvertes exceptionnelles, des conseils techniques, des essais de mat\u00e9riel, ainsi que des rubriques sur l\u2019exploration urbaine (Urbex) et la recherche de min\u00e9raux. Si vous \u00eates passionn\u00e9 par l\u2019histoire enfouie sous nos pieds,\u00a0<strong>Tr\u00e9sors<\/strong>\u00a0est fait pour vous !<\/p>","protected":false},"excerpt":{"rendered":"<p>Tr\u00e9sors, le magazine des Fouilleurs\u00a0est un incontournable pour les passionn\u00e9s de d\u00e9tection de m\u00e9taux, d\u2019orpillage et de p\u00eache \u00e0 l\u2019aimant. Paru tous les trois mois en kiosque depuis\u00a02005, ce magazine r\u00e9f\u00e9rence d\u00e9voile les tr\u00e9sors d\u00e9couverts en France, que ce soit avec un d\u00e9tecteur de m\u00e9taux, un aimant ou une b\u00e2t\u00e9e. Dans chaque num\u00e9ro, vous trouverez [&hellip;]<\/p>\n","protected":false},"featured_media":10559,"template":"","meta":[],"product_brand":[],"product_cat":[550,87],"product_tag":[1690],"class_list":["post-10560","product","type-product","status-publish","has-post-thumbnail","product_cat-archeologie","product_cat-multimedia-informatique","product_tag-magazine","pa_titre-tresors-le-magazine-des-fouilleurs","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/product\/10560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/product\/10560\/revisions"}],"predecessor-version":[{"id":31191,"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/product\/10560\/revisions\/31191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/media\/10559"}],"wp:attachment":[{"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/media?parent=10560"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/product_brand?post=10560"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/product_cat?post=10560"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mesmedias.be\/nl\/wp-json\/wp\/v2\/product_tag?post=10560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}